{"id":13215,"date":"2023-10-20T12:11:19","date_gmt":"2023-10-20T10:11:19","guid":{"rendered":"https:\/\/www.mtcomax.cz\/products\/coil-coating-line\/profiling\/"},"modified":"2025-09-30T10:36:33","modified_gmt":"2025-09-30T08:36:33","slug":"profilazione","status":"publish","type":"page","link":"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/","title":{"rendered":"Profilazione"},"content":{"rendered":"<h2 style=\"text-align: center;\">Produciamo 8 tipi di coperture in 20 diverse versioni<\/h2>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-13215 gallery-columns-4 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-alukryt.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-alukryt-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-13976\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-srcset=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-alukryt-300x300.jpg 300w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-alukryt-150x150.jpg 150w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-alukryt-768x768.jpg 768w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-alukryt.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13976'>\n\t\t\t\tCOMAX ALUKRYT\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-taska.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-taska-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-13972\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-srcset=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-taska-300x300.jpg 300w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-taska-150x150.jpg 150w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-taska-768x768.jpg 768w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-taska.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13972'>\n\t\t\t\tCOMAX TILE\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-falc.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-falc-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-13968\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-srcset=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-falc-300x300.jpg 300w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-falc-150x150.jpg 150w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-falc-768x768.jpg 768w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-falc.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13968'>\n\t\t\t\tCOMAX FALC\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-klik-31.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-klik-31-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-13964\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-srcset=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-klik-31-300x300.jpg 300w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-klik-31-150x150.jpg 150w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-klik-31-768x768.jpg 768w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-klik-31.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13964'>\n\t\t\t\tCOMAX KLIK\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-trapez.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-trapez-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-13960\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-srcset=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-trapez-300x300.jpg 300w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-trapez-150x150.jpg 150w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-trapez-768x768.jpg 768w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-trapez.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13960'>\n\t\t\t\tCOMAX TRAPEZE\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-vlnka.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-vlnka-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-13956\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-srcset=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-vlnka-300x300.jpg 300w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-vlnka-150x150.jpg 150w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-vlnka-768x768.jpg 768w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-vlnka.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13956'>\n\t\t\t\tCOMAX WAVE\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-boco330.png'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-boco330-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-13952\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-srcset=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-boco330-300x300.png 300w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-boco330-150x150.png 150w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-boco330-768x768.png 768w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-boco330.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13952'>\n\t\t\t\tCOMAX BoCo 330\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2024\/04\/comax-combo.png'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2024\/04\/comax-combo-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" aria-describedby=\"gallery-1-13758\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-srcset=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2024\/04\/comax-combo-300x300.png 300w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2024\/04\/comax-combo-150x150.png 150w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2024\/04\/comax-combo-768x768.png 768w, https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2024\/04\/comax-combo.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-13758'>\n\t\t\t\tCOMAX ComBo 430\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a class=\"btn --secondary\" href=\"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/dettagli-di-contatto\/\" target=\"blank\" rel=\"noopener\">Contact us<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le coperture metalliche ceche di qualit\u00e0 nascono alla COMAX<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13205,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pages\/page-blocks.php","meta":{"footnotes":""},"class_list":["post-13215","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Profilazione | METAL TRADE COMAX, a.s.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Profilazione | METAL TRADE COMAX, a.s.\" \/>\n<meta property=\"og:description\" content=\"Le coperture metalliche ceche di qualit\u00e0 nascono alla COMAX\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/\" \/>\n<meta property=\"og:site_name\" content=\"METAL TRADE COMAX, a.s.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/metaltradecomax\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-30T08:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-alukryt-300x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Profilazione | METAL TRADE COMAX, a.s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/","og_locale":"it_IT","og_type":"article","og_title":"Profilazione | METAL TRADE COMAX, a.s.","og_description":"Le coperture metalliche ceche di qualit\u00e0 nascono alla COMAX","og_url":"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/","og_site_name":"METAL TRADE COMAX, a.s.","article_publisher":"https:\/\/www.facebook.com\/metaltradecomax\/","article_modified_time":"2025-09-30T08:36:33+00:00","og_image":[{"url":"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/comax-alukryt-300x300.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/","url":"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/","name":"Profilazione | METAL TRADE COMAX, a.s.","isPartOf":{"@id":"https:\/\/comax.brilo.work\/#website"},"datePublished":"2023-10-20T10:11:19+00:00","dateModified":"2025-09-30T08:36:33+00:00","breadcrumb":{"@id":"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/profilazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/www.mtcomax.cz\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.mtcomax.cz\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Coil coating line","item":"https:\/\/www.mtcomax.cz\/it\/prodotti\/coil-coating-line\/"},{"@type":"ListItem","position":4,"name":"Profilazione"}]},{"@type":"WebSite","@id":"https:\/\/comax.brilo.work\/#website","url":"https:\/\/comax.brilo.work\/","name":"METAL TRADE COMAX, a.s.","description":"","publisher":{"@id":"https:\/\/comax.brilo.work\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comax.brilo.work\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comax.brilo.work\/#organization","name":"METAL TRADE COMAX, a.s.","url":"https:\/\/comax.brilo.work\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comax.brilo.work\/#\/schema\/logo\/image\/","url":"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/mtc-favikon-2.jpg","contentUrl":"https:\/\/www.mtcomax.cz\/wp-content\/uploads\/2025\/09\/mtc-favikon-2.jpg","width":500,"height":500,"caption":"METAL TRADE COMAX, a.s."},"image":{"@id":"https:\/\/comax.brilo.work\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/metaltradecomax\/","https:\/\/www.instagram.com\/metal_trade_comax\/","https:\/\/www.linkedin.com\/company\/metal-trade-comax-a-s\/","https:\/\/www.youtube.com\/@metaltradecomaxa.s.8970"]}]}},"_links":{"self":[{"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/pages\/13215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/comments?post=13215"}],"version-history":[{"count":7,"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/pages\/13215\/revisions"}],"predecessor-version":[{"id":13982,"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/pages\/13215\/revisions\/13982"}],"up":[{"embeddable":true,"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/pages\/13205"}],"wp:attachment":[{"href":"https:\/\/www.mtcomax.cz\/it\/wp-json\/wp\/v2\/media?parent=13215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}